{"id":185,"count":1,"description":"","link":"https:\/\/www.lausitzer-museenland.de\/en\/ort\/heimatstube-gross-koelzig\/","name":"Local history room Gro\u00df K\u00f6lzig","slug":"heimatstube-gross-koelzig","taxonomy":"event-venue","meta":[],"_links":{"self":[{"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/event-venue\/185"}],"collection":[{"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/event-venue"}],"about":[{"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/taxonomies\/event-venue"}]}}