{"id":55341,"date":"2024-10-02T09:31:18","date_gmt":"2024-10-02T07:31:18","guid":{"rendered":"https:\/\/www.lausitzer-museenland.de\/?p=55341"},"modified":"2024-10-02T11:49:09","modified_gmt":"2024-10-02T09:49:09","slug":"wahl-des-rates-fuer-angelegenheiten-der-sorben-wenden-2024","status":"publish","type":"post","link":"https:\/\/www.lausitzer-museenland.de\/en\/election-of-the-council-for-affairs-of-the-sorbians-2024\/","title":{"rendered":"Election of the Council for Sorbs\/Wends Affairs 2024"},"content":{"rendered":"<p>Die Domowina, der Dachverband der Sorben, ruft alle B\u00fcrgerinnen und B\u00fcrger dazu auf, sich an der Wahl des neuen Rates f\u00fcr Angelegenheiten der Sorben\/Wenden in Brandenburg zu beteiligen.<!--more--> Diese Wahl ist von gro\u00dfer Bedeutung f\u00fcr die Zukunft der sorbischen Gemeinschaft und Kultur in Brandenburg.<\/p>\n<p>Der Rat f\u00fcr Angelegenheiten der Sorben\/Wenden agiert als beratendes Gremium beim Landtag Brandenburg und setzt sich f\u00fcr die Einhaltung sowie die Verbesserung der Rechte der Sorben und Wenden ein. Er vertritt deren Interessen auf politischer Ebene und sorgt daf\u00fcr, dass sorbische\/wendische Belange in Potsdam\/P\u00f3dstupim geh\u00f6rt und als wichtig wahrgenommen werden. Eine hohe Wahlbeteiligung st\u00e4rkt die Stimme der Sorben und Wenden in den politischen Entscheidungsprozessen.<\/p>\n<p>Wichtige Termine zur Wahl:<\/p>\n<ul style=\"list-style-type: circle;\">\n<li>Bis zum 28. Oktober 2024 m\u00fcssen Wahlvorschl\u00e4ge schriftlich in der Gesch\u00e4ftsstelle des Wahlausschusses eingereicht werden.<\/li>\n<li>Bis zum 8. Dezember 2024 ist die Registrierung als W\u00e4hlerin oder W\u00e4hler m\u00f6glich.<\/li>\n<li>Bis zum 15. Dezember 2024 um 12:00 Uhr muss die Briefwahl abgeschlossen sein.<\/li>\n<\/ul>\n<p>Alle Wahl- und Informationsunterlagen stehen online unter [wolba-serbska-rada.de](http:\/\/wolba-serbska-rada.de) zur Verf\u00fcgung. Alternativ k\u00f6nnen diese auch per E-Mail an info@wolba-serbska-rada.de beim Wahlausschuss angefordert werden.<\/p>\n<p>Kontakt:<br \/>\nWahlausschuss f\u00fcr die Wahl des 7. Rates f\u00fcr Angelegenheiten der Sorben\/Wenden beim Landtag Brandenburg<br \/>\nFeuerwehrhof Tylcyc<br \/>\nHauptstra\u00dfe 44<br \/>\n03096 Dissen-Striesow\/De\u0161no-Strja\u017eow<br \/>\nTel.: 01525 5417883<\/p>\n<p>Stimmen aus der Region:<\/p>\n<p>Der Spree-Nei\u00dfe-Landrat Harald Altekr\u00fcger hat bereits seinen Antrag auf Eintragung ins W\u00e4hlerverzeichnis ausgef\u00fcllt und wendet sich mit einem Appell an die B\u00fcrgerinnen und B\u00fcrger:<br \/>\n\u201eWer sich den Sorben und Wenden in Brandenburg zugeh\u00f6rig f\u00fchlt, m\u00f6chte ich dazu aufrufen, die Aufnahme ins W\u00e4hlerverzeichnis zu beantragen und an der Wahl des Sorbenrates teilzunehmen. Dank des Engagements der Ratsmitglieder k\u00f6nnen die W\u00e4hlerinnen und W\u00e4hler einen wichtigen Beitrag zur Ber\u00fccksichtigung sorbischer\/wendischer Interessen im Landtag leisten. Vor diesem Hintergrund lohnt es sich, bei der Wahl seine Stimme abzugeben.\u201c<\/p>\n<p>Die Wahl erfolgt ausschlie\u00dflich per Briefwahl, und eine Eintragung ins W\u00e4hlerverzeichnis ist noch bis zum **8. Dezember 2024** m\u00f6glich.<\/p>\n<p>Jetzt aktiv werden und die Zukunft der sorbischen\/wendischen Gemeinschaft mitgestalten!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domowina, the umbrella organisation of the Sorbs, is calling on all citizens to take part in the election of the new Council for Sorbs\/Wends in Brandenburg.<\/p>","protected":false},"author":13,"featured_media":55344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/posts\/55341"}],"collection":[{"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/comments?post=55341"}],"version-history":[{"count":5,"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/posts\/55341\/revisions"}],"predecessor-version":[{"id":55491,"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/posts\/55341\/revisions\/55491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/media\/55344"}],"wp:attachment":[{"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/media?parent=55341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/categories?post=55341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lausitzer-museenland.de\/en\/wp-json\/wp\/v2\/tags?post=55341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}